{"id":18295,"date":"2019-05-21T15:00:51","date_gmt":"2019-05-21T18:00:51","guid":{"rendered":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13.jpeg"},"modified":"2019-05-21T15:00:51","modified_gmt":"2019-05-21T18:00:51","slug":"13","status":"inherit","type":"attachment","link":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/13\/","title":{"rendered":"13"},"author":6,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13.jpeg'><img width=\"300\" height=\"225\" src=\"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-300x225.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-300x225.jpeg 300w, https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-768x576.jpeg 768w, https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-1024x768.jpeg 1024w, https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13.jpeg 1032w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1032,"height":774,"file":"2019\/05\/13.jpeg","sizes":{"thumbnail":{"file":"13-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-150x150.jpeg"},"medium":{"file":"13-300x225.jpeg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-300x225.jpeg"},"medium_large":{"file":"13-768x576.jpeg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-768x576.jpeg"},"large":{"file":"13-1024x768.jpeg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-1024x768.jpeg"},"widgets_image_size":{"file":"13-800x774.jpeg","width":800,"height":774,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-800x774.jpeg"},"post-thumbnail":{"file":"13-720x380.jpeg","width":720,"height":380,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-720x380.jpeg"},"vantage-thumbnail-no-sidebar":{"file":"13-1032x380.jpeg","width":1032,"height":380,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-1032x380.jpeg"},"vantage-slide":{"file":"13-960x480.jpeg","width":960,"height":480,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-960x480.jpeg"},"vantage-carousel":{"file":"13-272x182.jpeg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-272x182.jpeg"},"vantage-grid-loop":{"file":"13-436x272.jpeg","width":436,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-436x272.jpeg"},"sow-carousel-default":{"file":"13-272x182.jpeg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-272x182.jpeg"},"meta-slider-resized-650x400":{"file":"13-650x400.jpeg","width":650,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-650x400.jpeg"},"meta-slider-resized-620x382":{"file":"13-620x382.jpeg","width":620,"height":382,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-620x382.jpeg"},"meta-slider-resized-400x246":{"file":"13-400x246.jpeg","width":400,"height":246,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13-400x246.jpeg"},"full":{"file":"13.jpeg","width":1032,"height":774,"mime_type":"image\/jpeg","source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2019\/05\/13.jpeg","_links":{"self":[{"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/media\/18295"}],"collection":[{"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/users\/6"}]}}