{"id":5091,"date":"2013-12-12T18:00:02","date_gmt":"2013-12-12T21:00:02","guid":{"rendered":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/?p=5091"},"modified":"2013-12-17T23:54:53","modified_gmt":"2013-12-18T02:54:53","slug":"convocatoria-mosconi","status":"publish","type":"post","link":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/2013\/12\/12\/convocatoria-mosconi\/","title":{"rendered":"Proyectos aprobados Convocatoria Mosconi &#8211; RSPU 3270\/13"},"content":{"rendered":"<p>Proyectos &#8220;Ing. Mosconi&#8221; de la SPU de la Naci\u00f3n ganados por la UNT.<\/p>\n<p>Acompa\u00f1amos Resoluci\u00f3n SPU 3270 de fecha 20 de noviembre de 2013, que aprueba los proyectos seleccionados para su financiamiento, presentados en la Convocatoria &#8220;Capacidades Cient\u00edfico Tecnol\u00f3gicas Universitarias para el Desarrollo Energ\u00e9tico&#8221; Ing. Enrique Mosconi:\u00a0 &#8211; <a href=\"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-content\/uploads\/sites\/9\/2013\/12\/RSPU32701311.pdf\" target=\"_blank\">Resoluci\u00f3n.pdf<\/a><\/p>\n<div id=\"dc_vk_code\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Proyectos &#8220;Ing. Mosconi&#8221; de la SPU de la Naci\u00f3n ganados por la UNT. Acompa\u00f1amos Resoluci\u00f3n SPU 3270 de fecha 20 de noviembre de 2013, que aprueba los proyectos seleccionados para su financiamiento, presentados en la Convocatoria &#8220;Capacidades Cient\u00edfico Tecnol\u00f3gicas Universitarias para el Desarrollo Energ\u00e9tico&#8221; Ing. Enrique Mosconi:\u00a0 &#8211; Resoluci\u00f3n.pdf<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5],"tags":[],"_links":{"self":[{"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/posts\/5091"}],"collection":[{"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/comments?post=5091"}],"version-history":[{"count":3,"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/posts\/5091\/revisions"}],"predecessor-version":[{"id":5095,"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/posts\/5091\/revisions\/5095"}],"wp:attachment":[{"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/media?parent=5091"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/categories?post=5091"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.facet.unt.edu.ar\/facetinforma\/wp-json\/wp\/v2\/tags?post=5091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}